{"id":2310,"date":"2026-05-10T08:24:04","date_gmt":"2026-05-10T08:24:04","guid":{"rendered":"https:\/\/rccgthekingspalace.org\/mission10\/?page_id=2310"},"modified":"2026-05-10T08:44:12","modified_gmt":"2026-05-10T08:44:12","slug":"mission-trip-interest-form","status":"publish","type":"page","link":"https:\/\/rccgthekingspalace.org\/mission10\/mission-trip-interest-form\/","title":{"rendered":"Mission Trip Interest Form"},"content":{"rendered":"<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style>\n                        <div class='gform_heading'>\n                            <h2 class=\"gform_title\">Mission Trip Interest Form<\/h2>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_1'  action='\/mission10\/wp-json\/wp\/v2\/pages\/2310' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><fieldset id=\"field_1_1\" class=\"gfield gfield--type-name gfield--input-type-name gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_1'>\n                            \n                            <span id='input_1_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_1_1_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_1_1_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_1_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.6' id='input_1_1_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_1_1_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_1_3\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_3'>Phone<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_3' id='input_1_3' type='tel' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_1_4\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Consent<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_4.1' id='input_1_4_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_1_4_1' >Give your consent to receive SMS messages by simply checking the box.<\/label><input type='hidden' name='input_4.2' value='Give your consent to receive SMS messages by simply checking the box.' class='gform_hidden' \/><input type='hidden' name='input_4.3' value='1' class='gform_hidden' \/><\/div><\/fieldset><fieldset id=\"field_1_8\" class=\"gfield gfield--type-date gfield--input-type-date gfield--input-type-datedropdown gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label' >Date Of Birth<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div id='input_1_8' class='ginput_container ginput_complex gform-grid-row'><div class='gfield_date_dropdown_month ginput_container ginput_container_date gform-grid-col' id='input_1_8_1_container'><label for='input_1_8_1' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Month<\/label><select name='input_8[]' id='input_1_8_1'   aria-required='true'  ><option value=''>Month<\/option><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><option value='6' >6<\/option><option value='7' >7<\/option><option value='8' >8<\/option><option value='9' >9<\/option><option value='10' >10<\/option><option value='11' >11<\/option><option value='12' >12<\/option><\/select><\/div><div class='gfield_date_dropdown_day ginput_container ginput_container_date gform-grid-col' id='input_1_8_2_container'><label for='input_1_8_2' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Day<\/label><select name='input_8[]' id='input_1_8_2'   aria-required='true'  ><option value=''>Day<\/option><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><option value='6' >6<\/option><option value='7' >7<\/option><option value='8' >8<\/option><option value='9' >9<\/option><option value='10' >10<\/option><option value='11' >11<\/option><option value='12' >12<\/option><option value='13' >13<\/option><option value='14' >14<\/option><option value='15' >15<\/option><option value='16' >16<\/option><option value='17' >17<\/option><option value='18' >18<\/option><option value='19' >19<\/option><option value='20' >20<\/option><option value='21' >21<\/option><option value='22' >22<\/option><option value='23' >23<\/option><option value='24' >24<\/option><option value='25' >25<\/option><option value='26' >26<\/option><option value='27' >27<\/option><option value='28' >28<\/option><option value='29' >29<\/option><option value='30' >30<\/option><option value='31' >31<\/option><\/select><\/div><div class='gfield_date_dropdown_year ginput_container ginput_container_date gform-grid-col' id='input_1_8_3_container'><label for='input_1_8_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Year<\/label><select name='input_8[]' id='input_1_8_3'   aria-required='true'  ><option value=''>Year<\/option><option value='2027' >2027<\/option><option value='2026' >2026<\/option><option value='2025' >2025<\/option><option value='2024' >2024<\/option><option value='2023' >2023<\/option><option value='2022' >2022<\/option><option value='2021' >2021<\/option><option value='2020' >2020<\/option><option value='2019' >2019<\/option><option value='2018' >2018<\/option><option value='2017' >2017<\/option><option value='2016' >2016<\/option><option value='2015' >2015<\/option><option value='2014' >2014<\/option><option value='2013' >2013<\/option><option value='2012' >2012<\/option><option value='2011' >2011<\/option><option value='2010' >2010<\/option><option value='2009' >2009<\/option><option value='2008' >2008<\/option><option value='2007' >2007<\/option><option value='2006' >2006<\/option><option value='2005' >2005<\/option><option value='2004' >2004<\/option><option value='2003' >2003<\/option><option value='2002' >2002<\/option><option value='2001' >2001<\/option><option value='2000' >2000<\/option><option value='1999' >1999<\/option><option value='1998' >1998<\/option><option value='1997' >1997<\/option><option value='1996' >1996<\/option><option value='1995' >1995<\/option><option value='1994' >1994<\/option><option value='1993' >1993<\/option><option value='1992' >1992<\/option><option value='1991' >1991<\/option><option value='1990' >1990<\/option><option value='1989' >1989<\/option><option value='1988' >1988<\/option><option value='1987' >1987<\/option><option value='1986' >1986<\/option><option value='1985' >1985<\/option><option value='1984' >1984<\/option><option value='1983' >1983<\/option><option value='1982' >1982<\/option><option value='1981' >1981<\/option><option value='1980' >1980<\/option><option value='1979' >1979<\/option><option value='1978' >1978<\/option><option value='1977' >1977<\/option><option value='1976' >1976<\/option><option value='1975' >1975<\/option><option value='1974' >1974<\/option><option value='1973' >1973<\/option><option value='1972' >1972<\/option><option value='1971' >1971<\/option><option value='1970' >1970<\/option><option value='1969' >1969<\/option><option value='1968' >1968<\/option><option value='1967' >1967<\/option><option value='1966' >1966<\/option><option value='1965' >1965<\/option><option value='1964' >1964<\/option><option value='1963' >1963<\/option><option value='1962' >1962<\/option><option value='1961' >1961<\/option><option value='1960' >1960<\/option><option value='1959' >1959<\/option><option value='1958' >1958<\/option><option value='1957' >1957<\/option><option value='1956' >1956<\/option><option value='1955' >1955<\/option><option value='1954' >1954<\/option><option value='1953' >1953<\/option><option value='1952' >1952<\/option><option value='1951' >1951<\/option><option value='1950' >1950<\/option><option value='1949' >1949<\/option><option value='1948' >1948<\/option><option value='1947' >1947<\/option><option value='1946' >1946<\/option><option value='1945' >1945<\/option><option value='1944' >1944<\/option><option value='1943' >1943<\/option><option value='1942' >1942<\/option><option value='1941' >1941<\/option><option value='1940' >1940<\/option><option value='1939' >1939<\/option><option value='1938' >1938<\/option><option value='1937' >1937<\/option><option value='1936' >1936<\/option><option value='1935' >1935<\/option><option value='1934' >1934<\/option><option value='1933' >1933<\/option><option value='1932' >1932<\/option><option value='1931' >1931<\/option><option value='1930' >1930<\/option><option value='1929' >1929<\/option><option value='1928' >1928<\/option><option value='1927' >1927<\/option><option value='1926' >1926<\/option><option value='1925' >1925<\/option><option value='1924' >1924<\/option><option value='1923' >1923<\/option><option value='1922' >1922<\/option><option value='1921' >1921<\/option><option value='1920' >1920<\/option><\/select><\/div><\/div><\/fieldset><fieldset id=\"field_1_7\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox gfield--width-full gfield_contains_required field_sublabel_below gfield--has-description field_description_above field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >MISSION TRIP INFORMATION<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='gfield_description' id='gfield_description_1_7'>Congratulations! You are here because you are ready to explore a missions trip with us in 2026. Now check all that applies to you below and we will be in touch:\n<\/div><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_1_7'><div class='gchoice gchoice_1_7_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_7.1' type='checkbox'  value='St. Vincent and the Grenadines (Throne of Grace Church): Aug 10-15, 2026'  id='choice_1_7_1'   aria-describedby=\"gfield_description_1_7\"\/>\n\t\t\t\t\t\t\t\t<label for='choice_1_7_1' id='label_1_7_1' class='gform-field-label gform-field-label--type-inline'>St. Vincent and the Grenadines (Throne of Grace Church): Aug 10-15, 2026<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_1_7_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_7.2' type='checkbox'  value='Not yet sure. I just want to be kept in the loop'  id='choice_1_7_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_1_7_2' id='label_1_7_2' class='gform-field-label gform-field-label--type-inline'>Not yet sure. I just want to be kept in the loop<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_1_9\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_9'>If you have ever participated in a Mission Trip, please briefly describe your experience:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_9' id='input_1_9' class='textarea medium'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_1_10\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_10'>Do you have a valid passport?<\/label><div class='ginput_container ginput_container_select'><select name='input_10' id='input_1_10' class='large gfield_select'     aria-invalid=\"false\" ><option value='' ><\/option><option value='YES' >YES<\/option><option value='NO' >NO<\/option><\/select><\/div><\/div><div id=\"field_1_12\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">REFERENCES<\/h3><div class='gsection_description' id='gfield_description_1_12'>List two (2) &#8211; three (3) individuals from this church who could be contacted for a personal reference. Do enter the correct phone and e-mail addresses of all references to ensure timely processing of your application. Thank you.\n\n<\/div><\/div><div id=\"field_1_16\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Reference #1:<\/h3><\/div><fieldset id=\"field_1_13\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_13'>\n                            \n                            <span id='input_1_13_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_13.3' id='input_1_13_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_1_13_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_1_13_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_13.6' id='input_1_13_6' value=''   aria-required='false'     \/>\n                                                    <label for='input_1_13_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_1_17\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_17'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_17' id='input_1_17' type='email' value='' class='medium'     aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_1_18\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_18'>Phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_18' id='input_1_18' type='tel' value='' class='medium'    aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_19\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Reference #2:<\/h3><\/div><fieldset id=\"field_1_21\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_21'>\n                            \n                            <span id='input_1_21_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_21.3' id='input_1_21_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_1_21_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_1_21_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_21.6' id='input_1_21_6' value=''   aria-required='false'     \/>\n                                                    <label for='input_1_21_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_1_22\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_22'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_22' id='input_1_22' type='email' value='' class='large'     aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_1_23\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_23'>Phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_23' id='input_1_23' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='ionEA6IbzxS2UzFVazMPeLNC+YQlDX44CtW7AsiUtcR6owd3taULwsZ1e+T51sZ0dMGGmGzGPYMoN9mU5L\/qa1SoW8Lfb9H90TWz97jUaoxVXc4=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJ7XCI0LjFcIjpcIjM4YTNiN2U4ZTVlMGFlYmM2Y2NiMmY1NTUyZjVmNThmXCIsXCI0LjJcIjpcIjc1MzgzYzEyYmVhMjZiMTkyMjE3OTUxNGM5M2Q2NWQ2XCIsXCI0LjNcIjpcIjM4YTNiN2U4ZTVlMGFlYmM2Y2NiMmY1NTUyZjVmNThmXCIsXCI3LjFcIjpcIjI5Y2IwY2M1MWNhNWVlMzM3ODc2NGFmNGM3MDkxZWYxXCIsXCI3LjJcIjpcImQ5MDcxODU0NGY3MmRkNzMwZjJjZWIzNGYyMjAxNjQ3XCIsXCIxMFwiOltcIjY4YTMzMWI3YjEzYWMwZTYyNDcxOWEwYWUzZGViNGI0XCIsXCI2ODg0OTNjNGJlMGNmNWIxNmNlNjcwYTU4M2YwNmI2N1wiLFwiN2UzMWFiZWE0OGQ0MDc1MDA2MjFkMjlhY2U4ZDkzN2ZcIl19IiwiMWFjNThlNTM3N2U0NWQxNzIxOWM3MTBjMTBmNThiNGMiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/rccgthekingspalace.org\/mission10\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/rccgthekingspalace.org\/mission10\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-2310","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/pages\/2310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/comments?post=2310"}],"version-history":[{"count":2,"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/pages\/2310\/revisions"}],"predecessor-version":[{"id":2312,"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/pages\/2310\/revisions\/2312"}],"wp:attachment":[{"href":"https:\/\/rccgthekingspalace.org\/mission10\/wp-json\/wp\/v2\/media?parent=2310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}